{"id":12175,"date":"2022-10-21T11:41:55","date_gmt":"2022-10-21T11:41:55","guid":{"rendered":"https:\/\/projectsofar.info\/aisuperior\/?post_type=blog&#038;p=12175"},"modified":"2023-12-07T16:58:43","modified_gmt":"2023-12-07T16:58:43","slug":"computer-vision-in-sports","status":"publish","type":"blog","link":"https:\/\/aisuperior.com\/fr\/blog\/computer-vision-in-sports\/","title":{"rendered":"Applications de vision par ordinateur dans le sport"},"content":{"rendered":"<p>La technologie de vision par ordinateur (CV) s\u2019est consid\u00e9rablement am\u00e9lior\u00e9e au cours des derni\u00e8res d\u00e9cennies. Selon la soci\u00e9t\u00e9 d&#039;analyse de march\u00e9 Tractica, le march\u00e9 mondial du mat\u00e9riel et de la vision par ordinateur devrait atteindre $48,6 milliards de dollars d&#039;ici 2022, contre seulement $6,6 milliards de dollars en 2015. La technologie est utilis\u00e9e dans diverses industries \u2013 de la construction aux soins de sant\u00e9 et, de plus en plus, le sport.<\/p>\n<p>Dans cet article, nous discuterons de ce qu&#039;est la vision par ordinateur et de la mani\u00e8re dont les progr\u00e8s dans ce secteur ont apport\u00e9 des avantages majeurs aux entra\u00eeneurs et aux athl\u00e8tes, notamment en mati\u00e8re d&#039;analyse des performances et de strat\u00e9gie.<\/p>\n<h3><span class=\"wp-block-heading\"><strong>Qu\u2019est-ce que la vision par ordinateur ?<\/strong><\/span><\/h3>\n<p>La vision par ordinateur est un sous-ensemble de l\u2019intelligence artificielle et de l\u2019apprentissage automatique (IA\/ML) qui apprend aux ordinateurs \u00e0 identifier et classer avec pr\u00e9cision les images comme le font les humains. Gr\u00e2ce au deep learning, un mod\u00e8le de ML qui utilise plusieurs couches de r\u00e9seaux de neurones, CV est capable de d\u00e9tecter et d&#039;organiser la relation entre les objets et leurs environnements. Il existe plusieurs mod\u00e8les de CV, mais les plus populaires sont la classification d&#039;images, la d\u00e9tection d&#039;objets, la segmentation d&#039;images (divisant les images en parties) et la reconnaissance faciale.<\/p>\n<p>Le Big Data a contribu\u00e9 \u00e0 la croissance de ce secteur, car les algorithmes apprennent de plus de 3 milliards d\u2019images partag\u00e9es en ligne. En cons\u00e9quence, les syst\u00e8mes CV actuels ont atteint une pr\u00e9cision de 99\u00a0%. C&#039;est pourquoi votre smartphone est capable d&#039;identifier quand prendre des photos en mode nuit ou quand passer \u00e0 la photographie culinaire en fonction de ce que voient les cam\u00e9ras.<\/p>\n<h3>Applications de la vision par ordinateur dans le sport<\/h3>\n<h3>Performances sportives am\u00e9lior\u00e9es bas\u00e9es sur le suivi des mouvements<\/h3>\n<p>En 2019, le g\u00e9ant de la technologie IBM a cr\u00e9\u00e9 un syst\u00e8me de coaching cognitif pour l&#039;\u00e9quipe nationale f\u00e9minine de football des \u00c9tats-Unis. Le syst\u00e8me utilise des s\u00e9quences vid\u00e9o des performances des joueurs pour fournir des commentaires en temps opportun. En analysant les mouvements de l&#039;athl\u00e8te, les entra\u00eeneurs peuvent identifier les domaines \u00e0 am\u00e9liorer et les athl\u00e8tes peuvent se concentrer sur l&#039;entra\u00eenement dans ces domaines mis en \u00e9vidence.<\/p>\n<p>La vision par ordinateur s&#039;est consid\u00e9rablement am\u00e9lior\u00e9e depuis lors pour suivre les mouvements des articulations et des membres, aidant ainsi les entra\u00eeneurs et les athl\u00e8tes \u00e0 comprendre l&#039;impact de l&#039;entra\u00eenement sur leurs performances. De plus, CV peut analyser les mouvements d&#039;un joueur pour identifier les facteurs de risque potentiels de blessures (par exemple, blessures \u00e0 la cheville et au poignet dues \u00e0 une mauvaise posture).<\/p>\n<h3 class=\"has-medium-font-size wp-block-heading\">Suivi des joueurs pour l&#039;analyse des performances<\/h3>\n<p>S\u2019il est assez simple de d\u00e9tecter les joueurs et les arbitres \u00e0 partir des flux de cam\u00e9ras, les identifier avec pr\u00e9cision est beaucoup plus difficile. Pour augmenter la pr\u00e9cision du suivi des joueurs, les syst\u00e8mes CV utilisent souvent de nombreux angles de cam\u00e9ra diff\u00e9rents sp\u00e9cifiquement \u00e0 cet effet. Gr\u00e2ce \u00e0 cette technique, CV peut identifier chaque joueur et analyser ses poses, fournissant ainsi des informations pr\u00e9cieuses sur les performances du jeu en direct et en temps r\u00e9el.<\/p>\n<p>De plus, le journalisme sportif b\u00e9n\u00e9ficie d\u2019un suivi pr\u00e9cis des joueurs. Les donn\u00e9es peuvent \u00eatre utilis\u00e9es pour fournir des strat\u00e9gies plus approfondies et des analyses post-match, offrant ainsi aux t\u00e9l\u00e9spectateurs un contenu \u00e9ducatif mais divertissant. Parce que le CV a la capacit\u00e9 de diff\u00e9rencier les joueurs, les journalistes sportifs peuvent souligner pourquoi certains athl\u00e8tes sont plus performants que d\u2019autres.<\/p>\n<h3 class=\"has-medium-font-size wp-block-heading\">Suivi de balle<\/h3>\n<p>L&#039;une des technologies CV les plus utilis\u00e9es pour le suivi des balles est le HawkEye du tennis. Ce syst\u00e8me aide les arbitres \u00e0 identifier avec pr\u00e9cision o\u00f9 la balle a atterri, leur permettant ainsi de prendre des d\u00e9cisions fond\u00e9es sur des preuves. Les outils de suivi de balle peuvent aider des sports tels que le cricket, le badminton, le baseball, le basket-ball et le football \u00e0 enregistrer les mouvements en 3D, montrant o\u00f9 la balle frappe avec pr\u00e9cision et m\u00eame pr\u00e9dire o\u00f9 elle ira en fonction de la position du joueur.<\/p>\n<p>Dans le football, la FIFA a collabor\u00e9 avec HawkEye pour installer une technologie sur la ligne de but dans les grands stades gr\u00e2ce \u00e0 un syst\u00e8me CV \u00e0 7 cam\u00e9ras. Le syst\u00e8me utilise des cam\u00e9ras \u00e0 grande vitesse couvrant chaque zone d&#039;objectif et capables de d\u00e9tecter les objets en mouvement en fonction de la zone, de la couleur et de la forme. L&#039;outil CV a un taux d&#039;erreur de 1,5 centim\u00e8tre et une vitesse de d\u00e9tection de 1 seconde, permettant aux arbitres de prendre des d\u00e9cisions en temps r\u00e9el.<br \/>\n<span class=\"wp-block-heading\">D\u00e9fis et limites de la vision par ordinateur<\/span><br \/>\nM\u00eame si la technologie CV a parcouru un long chemin, elle ne peut toujours pas rivaliser avec l&#039;\u0153il humain. S\u2019il peut d\u00e9tecter les mouvements, il a encore du mal \u00e0 analyser certaines postures complexes ou \u00e0 d\u00e9terminer quel joueur est tel lors des collisions et de certaines interactions. Parfois, les \u00e9quipements (notamment les nouveaux) confondent ces cam\u00e9ras et capteurs.<\/p>\n<p>N\u00e9anmoins, les entreprises technologiques peaufinent constamment leurs technologies de CV pour rem\u00e9dier \u00e0 ces limitations. Par exemple, le traitement des images est am\u00e9lior\u00e9 pour mieux distinguer les joueurs des objets au premier plan. \u00c0 mesure que le sport professionnel devient plus comp\u00e9titif, les solutions de CV seront affin\u00e9es et \u00e9tendues pour fournir de meilleures analyses de performances.<\/p>\n<h3><span class=\"wp-block-heading\"><strong>Comment AI Superior peut vous aider<\/strong><\/span><\/h3>\n<p>Votre entreprise a besoin de solutions de vision par ordinateur pour booster vos performances ? chez AI Superior, nous pouvons vous aider \u00e0 identifier les processus que vous pouvez automatiser gr\u00e2ce \u00e0 des outils et syst\u00e8mes de CV, notamment le traitement et la segmentation d&#039;images, la reconnaissance faciale et optique de caract\u00e8res et la d\u00e9tection d&#039;objets.<\/p>","protected":false},"excerpt":{"rendered":"<p>Computer vision (CV) technology has improved dramatically over the past decades. According to market intelligence firm Tractica, the global computer vision and hardware market is expected to reach USD $48.6 billion by 2022 from just USD $6.6 billion in 2015. The technology is being used in various industries \u2013 from construction to healthcare and, increasingly, [&hellip;]<\/p>\n","protected":false},"featured_media":12176,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"categories":[16],"class_list":["post-12175","blog","type-blog","status-publish","has-post-thumbnail","hentry","category-computer-vision","blog_category-computer-vision"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Computer Vision Applications in Sports - aisuperior<\/title>\n<meta name=\"description\" content=\"Discover how computer vision technology is revolutionizing sports with enhanced performance analysis, player tracking, and ball tracking.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aisuperior.com\/fr\/blog\/computer-vision-in-sports\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Computer Vision Applications in Sports - aisuperior\" \/>\n<meta property=\"og:description\" content=\"Discover how computer vision technology is revolutionizing sports with enhanced performance analysis, player tracking, and ball tracking.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aisuperior.com\/fr\/blog\/computer-vision-in-sports\/\" \/>\n<meta property=\"og:site_name\" content=\"aisuperior\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aisuperior\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-07T16:58:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aisuperior.com\/wp-content\/uploads\/2023\/09\/emilio-garcia-AWdCgDDedH0-unsplash-1024x598-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"598\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@aisuperior\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aisuperior.com\\\/blog\\\/computer-vision-in-sports\\\/\",\"url\":\"https:\\\/\\\/aisuperior.com\\\/blog\\\/computer-vision-in-sports\\\/\",\"name\":\"Computer Vision Applications in Sports - aisuperior\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aisuperior.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aisuperior.com\\\/blog\\\/computer-vision-in-sports\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aisuperior.com\\\/blog\\\/computer-vision-in-sports\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aisuperior.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/emilio-garcia-AWdCgDDedH0-unsplash-1024x598-1.jpg\",\"datePublished\":\"2022-10-21T11:41:55+00:00\",\"dateModified\":\"2023-12-07T16:58:43+00:00\",\"description\":\"Discover how computer vision technology is revolutionizing sports with enhanced performance analysis, player tracking, and ball tracking.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aisuperior.com\\\/blog\\\/computer-vision-in-sports\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aisuperior.com\\\/blog\\\/computer-vision-in-sports\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aisuperior.com\\\/blog\\\/computer-vision-in-sports\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aisuperior.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/emilio-garcia-AWdCgDDedH0-unsplash-1024x598-1.jpg\",\"contentUrl\":\"https:\\\/\\\/aisuperior.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/emilio-garcia-AWdCgDDedH0-unsplash-1024x598-1.jpg\",\"width\":1024,\"height\":598},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aisuperior.com\\\/blog\\\/computer-vision-in-sports\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aisuperior.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blogs\",\"item\":\"https:\\\/\\\/aisuperior.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Computer Vision Applications in Sports\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aisuperior.com\\\/#website\",\"url\":\"https:\\\/\\\/aisuperior.com\\\/\",\"name\":\"aisuperior\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/aisuperior.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aisuperior.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aisuperior.com\\\/#organization\",\"name\":\"aisuperior\",\"url\":\"https:\\\/\\\/aisuperior.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aisuperior.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aisuperior.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo-1.png.webp\",\"contentUrl\":\"https:\\\/\\\/aisuperior.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo-1.png.webp\",\"width\":320,\"height\":59,\"caption\":\"aisuperior\"},\"image\":{\"@id\":\"https:\\\/\\\/aisuperior.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aisuperior\",\"https:\\\/\\\/x.com\\\/aisuperior\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ai-superior\",\"https:\\\/\\\/www.instagram.com\\\/ai_superior\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Applications de vision par ordinateur dans le sport - aisuperior","description":"D\u00e9couvrez comment la technologie de vision par ordinateur r\u00e9volutionne le sport avec une analyse am\u00e9lior\u00e9e des performances, un suivi des joueurs et un suivi du ballon.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aisuperior.com\/fr\/blog\/computer-vision-in-sports\/","og_locale":"fr_FR","og_type":"article","og_title":"Computer Vision Applications in Sports - aisuperior","og_description":"Discover how computer vision technology is revolutionizing sports with enhanced performance analysis, player tracking, and ball tracking.","og_url":"https:\/\/aisuperior.com\/fr\/blog\/computer-vision-in-sports\/","og_site_name":"aisuperior","article_publisher":"https:\/\/www.facebook.com\/aisuperior","article_modified_time":"2023-12-07T16:58:43+00:00","og_image":[{"width":1024,"height":598,"url":"https:\/\/aisuperior.com\/wp-content\/uploads\/2023\/09\/emilio-garcia-AWdCgDDedH0-unsplash-1024x598-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@aisuperior","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aisuperior.com\/blog\/computer-vision-in-sports\/","url":"https:\/\/aisuperior.com\/blog\/computer-vision-in-sports\/","name":"Applications de vision par ordinateur dans le sport - aisuperior","isPartOf":{"@id":"https:\/\/aisuperior.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aisuperior.com\/blog\/computer-vision-in-sports\/#primaryimage"},"image":{"@id":"https:\/\/aisuperior.com\/blog\/computer-vision-in-sports\/#primaryimage"},"thumbnailUrl":"https:\/\/aisuperior.com\/wp-content\/uploads\/2023\/09\/emilio-garcia-AWdCgDDedH0-unsplash-1024x598-1.jpg","datePublished":"2022-10-21T11:41:55+00:00","dateModified":"2023-12-07T16:58:43+00:00","description":"D\u00e9couvrez comment la technologie de vision par ordinateur r\u00e9volutionne le sport avec une analyse am\u00e9lior\u00e9e des performances, un suivi des joueurs et un suivi du ballon.","breadcrumb":{"@id":"https:\/\/aisuperior.com\/blog\/computer-vision-in-sports\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aisuperior.com\/blog\/computer-vision-in-sports\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aisuperior.com\/blog\/computer-vision-in-sports\/#primaryimage","url":"https:\/\/aisuperior.com\/wp-content\/uploads\/2023\/09\/emilio-garcia-AWdCgDDedH0-unsplash-1024x598-1.jpg","contentUrl":"https:\/\/aisuperior.com\/wp-content\/uploads\/2023\/09\/emilio-garcia-AWdCgDDedH0-unsplash-1024x598-1.jpg","width":1024,"height":598},{"@type":"BreadcrumbList","@id":"https:\/\/aisuperior.com\/blog\/computer-vision-in-sports\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aisuperior.com\/"},{"@type":"ListItem","position":2,"name":"Blogs","item":"https:\/\/aisuperior.com\/blog\/"},{"@type":"ListItem","position":3,"name":"Computer Vision Applications in Sports"}]},{"@type":"WebSite","@id":"https:\/\/aisuperior.com\/#website","url":"https:\/\/aisuperior.com\/","name":"aisuperior","description":"","publisher":{"@id":"https:\/\/aisuperior.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aisuperior.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/aisuperior.com\/#organization","name":"aisuperior","url":"https:\/\/aisuperior.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aisuperior.com\/#\/schema\/logo\/image\/","url":"https:\/\/aisuperior.com\/wp-content\/uploads\/2026\/02\/logo-1.png.webp","contentUrl":"https:\/\/aisuperior.com\/wp-content\/uploads\/2026\/02\/logo-1.png.webp","width":320,"height":59,"caption":"aisuperior"},"image":{"@id":"https:\/\/aisuperior.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aisuperior","https:\/\/x.com\/aisuperior","https:\/\/www.linkedin.com\/company\/ai-superior","https:\/\/www.instagram.com\/ai_superior\/"]}]}},"_links":{"self":[{"href":"https:\/\/aisuperior.com\/fr\/wp-json\/wp\/v2\/blog\/12175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aisuperior.com\/fr\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/aisuperior.com\/fr\/wp-json\/wp\/v2\/types\/blog"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aisuperior.com\/fr\/wp-json\/wp\/v2\/media\/12176"}],"wp:attachment":[{"href":"https:\/\/aisuperior.com\/fr\/wp-json\/wp\/v2\/media?parent=12175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aisuperior.com\/fr\/wp-json\/wp\/v2\/categories?post=12175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}